{"id":255,"date":"2016-05-10T14:58:15","date_gmt":"2016-05-10T13:58:15","guid":{"rendered":"https:\/\/www.berger.ca\/es\/?page_id=255"},"modified":"2025-07-08T09:29:00","modified_gmt":"2025-07-08T14:29:00","slug":"servicios","status":"publish","type":"page","link":"https:\/\/www.berger.ca\/es\/servicios\/","title":{"rendered":"Servicios"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-hub.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-255","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Servicios - Berger - ES<\/title>\n<meta name=\"description\" content=\"Nuestro equipo multidisciplinario solo tiene un deseo: oferta de servicios personalizados a lo largo de sus procesos de producci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.berger.ca\/es\/servicios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servicios - Berger - ES\" \/>\n<meta property=\"og:description\" content=\"Nuestro equipo multidisciplinario solo tiene un deseo: oferta de servicios personalizados a lo largo de sus procesos de producci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.berger.ca\/es\/servicios\/\" \/>\n<meta property=\"og:site_name\" content=\"Berger - ES\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/berger.ca\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-08T14:29:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@berger_ca\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.berger.ca\\\/es\\\/servicios\\\/\",\"url\":\"https:\\\/\\\/www.berger.ca\\\/es\\\/servicios\\\/\",\"name\":\"Servicios - Berger - ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.berger.ca\\\/es\\\/#website\"},\"datePublished\":\"2016-05-10T13:58:15+00:00\",\"dateModified\":\"2025-07-08T14:29:00+00:00\",\"description\":\"Nuestro equipo multidisciplinario solo tiene un deseo: oferta de servicios personalizados a lo largo de sus procesos de producci\u00f3n.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.berger.ca\\\/es\\\/servicios\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.berger.ca\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.berger.ca\\\/es\\\/\",\"name\":\"Berger - ES\",\"description\":\"Un site utilisant Sites Berger\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.berger.ca\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.berger.ca\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.berger.ca\\\/es\\\/#organization\",\"name\":\"Berger\",\"url\":\"https:\\\/\\\/www.berger.ca\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.berger.ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.berger.ca\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/07\\\/berger_logo_coul_seul.png\",\"contentUrl\":\"https:\\\/\\\/www.berger.ca\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/07\\\/berger_logo_coul_seul.png\",\"width\":1257,\"height\":1156,\"caption\":\"Berger\"},\"image\":{\"@id\":\"https:\\\/\\\/www.berger.ca\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/berger.ca\\\/\",\"https:\\\/\\\/x.com\\\/berger_ca\",\"https:\\\/\\\/www.instagram.com\\\/bergermixes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/berger-peat-moss-ltd-\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/bergerpeatmoss\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/tourbieresberger\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servicios - Berger - ES","description":"Nuestro equipo multidisciplinario solo tiene un deseo: oferta de servicios personalizados a lo largo de sus procesos de producci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.berger.ca\/es\/servicios\/","og_locale":"es_ES","og_type":"article","og_title":"Servicios - Berger - ES","og_description":"Nuestro equipo multidisciplinario solo tiene un deseo: oferta de servicios personalizados a lo largo de sus procesos de producci\u00f3n.","og_url":"https:\/\/www.berger.ca\/es\/servicios\/","og_site_name":"Berger - ES","article_publisher":"https:\/\/www.facebook.com\/berger.ca\/","article_modified_time":"2025-07-08T14:29:00+00:00","twitter_card":"summary_large_image","twitter_site":"@berger_ca","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.berger.ca\/es\/servicios\/","url":"https:\/\/www.berger.ca\/es\/servicios\/","name":"Servicios - Berger - ES","isPartOf":{"@id":"https:\/\/www.berger.ca\/es\/#website"},"datePublished":"2016-05-10T13:58:15+00:00","dateModified":"2025-07-08T14:29:00+00:00","description":"Nuestro equipo multidisciplinario solo tiene un deseo: oferta de servicios personalizados a lo largo de sus procesos de producci\u00f3n.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.berger.ca\/es\/servicios\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.berger.ca\/es\/#website","url":"https:\/\/www.berger.ca\/es\/","name":"Berger - ES","description":"Un site utilisant Sites Berger","publisher":{"@id":"https:\/\/www.berger.ca\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.berger.ca\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.berger.ca\/es\/#organization","name":"Berger","url":"https:\/\/www.berger.ca\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.berger.ca\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.berger.ca\/es\/wp-content\/uploads\/sites\/3\/2016\/07\/berger_logo_coul_seul.png","contentUrl":"https:\/\/www.berger.ca\/es\/wp-content\/uploads\/sites\/3\/2016\/07\/berger_logo_coul_seul.png","width":1257,"height":1156,"caption":"Berger"},"image":{"@id":"https:\/\/www.berger.ca\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/berger.ca\/","https:\/\/x.com\/berger_ca","https:\/\/www.instagram.com\/bergermixes\/","https:\/\/www.linkedin.com\/company\/berger-peat-moss-ltd-\/","https:\/\/www.pinterest.com\/bergerpeatmoss\/","https:\/\/www.youtube.com\/user\/tourbieresberger"]}]}},"_links":{"self":[{"href":"https:\/\/www.berger.ca\/es\/wp-json\/wp\/v2\/pages\/255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.berger.ca\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.berger.ca\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.berger.ca\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.berger.ca\/es\/wp-json\/wp\/v2\/comments?post=255"}],"version-history":[{"count":24,"href":"https:\/\/www.berger.ca\/es\/wp-json\/wp\/v2\/pages\/255\/revisions"}],"predecessor-version":[{"id":5942,"href":"https:\/\/www.berger.ca\/es\/wp-json\/wp\/v2\/pages\/255\/revisions\/5942"}],"wp:attachment":[{"href":"https:\/\/www.berger.ca\/es\/wp-json\/wp\/v2\/media?parent=255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}